{"id":8398,"date":"2025-01-16T13:44:42","date_gmt":"2025-01-16T12:44:42","guid":{"rendered":"https:\/\/www.getemed.de\/?p=8398"},"modified":"2025-01-16T14:06:07","modified_gmt":"2025-01-16T13:06:07","slug":"besuchen-sie-uns-auf-der-arab-health-2025","status":"publish","type":"post","link":"https:\/\/www.getemed.de\/de\/besuchen-sie-uns-auf-der-arab-health-2025\/","title":{"rendered":"Besuchen Sie uns auf der Arab Health 2025"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"8398\" class=\"elementor elementor-8398\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-24ba105c elementor-section-height-min-height elementor-section-items-top elementor-section-boxed elementor-section-height-default\" data-id=\"24ba105c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-23f41a10\" data-id=\"23f41a10\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2a721db6 elementor-widget elementor-widget-heading\" data-id=\"2a721db6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Besuchen Sie uns auf der Arab Health 2025<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-61d250a3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"61d250a3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3202445c\" data-id=\"3202445c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6cbb9589 elementor-widget elementor-widget-text-editor\" data-id=\"6cbb9589\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>16. Januar 2025<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-323cba0e elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"323cba0e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Bei der diesj\u00e4hrigen Arab Health vom 27.-30.01.25 wird GETEMED gemeinsam mit seinen Partnern auf dem Gemeinschaftsstand von Th\u00fcringen seine neuesten Entwicklungen, Produkte und Services in den Bereichen Telemonitoring und Holter EKG vorstellen.<\/p><p>Wir laden alle herzlich ein, uns im World Trade Center in Dubai am Stand Z6F70 zu besuchen.<\/p><p>Sie finden uns in der Halle Z6 am Stand Z6F70 <a id=\"link2\" href=\"https:\/\/www.expocad.com\/host\/fx\/informa\/arhe25\/exfx.html?zoomto=Z6.F70\" target=\"_blank\" rel=\"noopener\">https:\/\/www.expocad.com\/host\/fx\/informa\/arhe25\/exfx.html?zoomto=Z6.F70<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5dec642e\" data-id=\"5dec642e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-579f909f elementor-widget elementor-widget-image\" data-id=\"579f909f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1187\" height=\"667\" src=\"https:\/\/www.getemed.de\/wp-content\/uploads\/Dubai.png\" class=\"attachment-2048x2048 size-2048x2048 wp-image-8401\" alt=\"\" srcset=\"https:\/\/www.getemed.de\/wp-content\/uploads\/Dubai.png 1187w, https:\/\/www.getemed.de\/wp-content\/uploads\/Dubai-300x169.png 300w, https:\/\/www.getemed.de\/wp-content\/uploads\/Dubai-1024x575.png 1024w, https:\/\/www.getemed.de\/wp-content\/uploads\/Dubai-150x84.png 150w, https:\/\/www.getemed.de\/wp-content\/uploads\/Dubai-768x432.png 768w, https:\/\/www.getemed.de\/wp-content\/uploads\/Dubai-18x10.png 18w\" sizes=\"(max-width: 1187px) 100vw, 1187px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Besuchen Sie uns auf der Arab Health 2025 16. Januar 2025 Bei der diesj\u00e4hrigen Arab Health vom 27.-30.01.25 wird GETEMED gemeinsam mit seinen Partnern auf dem Gemeinschaftsstand von Th\u00fcringen seine [&hellip;]<\/p>\n","protected":false},"author":219149283,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2710],"tags":[],"class_list":["post-8398","post","type-post","status-publish","format-standard","hentry","category-allgemein"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Besuchen Sie uns auf der Arab Health 2025 - Medizin- und Informationstechnik AG<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.getemed.de\/de\/besuchen-sie-uns-auf-der-arab-health-2025\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Besuchen Sie uns auf der Arab Health 2025 - Medizin- und Informationstechnik AG\" \/>\n<meta property=\"og:description\" content=\"Besuchen Sie uns auf der Arab Health 2025 16. Januar 2025 Bei der diesj\u00e4hrigen Arab Health vom 27.-30.01.25 wird GETEMED gemeinsam mit seinen Partnern auf dem Gemeinschaftsstand von Th\u00fcringen seine [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.getemed.de\/de\/besuchen-sie-uns-auf-der-arab-health-2025\/\" \/>\n<meta property=\"og:site_name\" content=\"Medizin- und Informationstechnik AG\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-16T12:44:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-16T13:06:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.getemed.de\/wp-content\/uploads\/Dubai.png\" \/>\n<meta name=\"author\" content=\"Vishwanath Diraviam\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Vishwanath Diraviam\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.getemed.de\\\/besuchen-sie-uns-auf-der-arab-health-2025\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.getemed.de\\\/besuchen-sie-uns-auf-der-arab-health-2025\\\/\"},\"author\":{\"name\":\"Vishwanath Diraviam\",\"@id\":\"https:\\\/\\\/www.getemed.de\\\/de\\\/#\\\/schema\\\/person\\\/89fb0914b510044ccc8cc7699942c7e1\"},\"headline\":\"Besuchen Sie uns auf der Arab Health 2025\",\"datePublished\":\"2025-01-16T12:44:42+00:00\",\"dateModified\":\"2025-01-16T13:06:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.getemed.de\\\/besuchen-sie-uns-auf-der-arab-health-2025\\\/\"},\"wordCount\":91,\"publisher\":{\"@id\":\"https:\\\/\\\/www.getemed.de\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.getemed.de\\\/besuchen-sie-uns-auf-der-arab-health-2025\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.getemed.de\\\/wp-content\\\/uploads\\\/Dubai.png\",\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.getemed.de\\\/besuchen-sie-uns-auf-der-arab-health-2025\\\/\",\"url\":\"https:\\\/\\\/www.getemed.de\\\/besuchen-sie-uns-auf-der-arab-health-2025\\\/\",\"name\":\"Besuchen Sie uns auf der Arab Health 2025 - Medizin- und Informationstechnik AG\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.getemed.de\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.getemed.de\\\/besuchen-sie-uns-auf-der-arab-health-2025\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.getemed.de\\\/besuchen-sie-uns-auf-der-arab-health-2025\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.getemed.de\\\/wp-content\\\/uploads\\\/Dubai.png\",\"datePublished\":\"2025-01-16T12:44:42+00:00\",\"dateModified\":\"2025-01-16T13:06:07+00:00\",\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.getemed.de\\\/besuchen-sie-uns-auf-der-arab-health-2025\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.getemed.de\\\/besuchen-sie-uns-auf-der-arab-health-2025\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.getemed.de\\\/wp-content\\\/uploads\\\/Dubai.png\",\"contentUrl\":\"https:\\\/\\\/www.getemed.de\\\/wp-content\\\/uploads\\\/Dubai.png\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.getemed.de\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.getemed.de\\\/de\\\/\",\"name\":\"GETEMED Medizin- und Informationstechnik AG\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.getemed.de\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.getemed.de\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.getemed.de\\\/de\\\/#organization\",\"name\":\"GETEMEDNMedizin- und Informationstechnik AG\",\"url\":\"https:\\\/\\\/www.getemed.de\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.getemed.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.getemed.de\\\/wp-content\\\/uploads\\\/Logo_GETEMED.png\",\"contentUrl\":\"https:\\\/\\\/www.getemed.de\\\/wp-content\\\/uploads\\\/Logo_GETEMED.png\",\"width\":1471,\"height\":305,\"caption\":\"GETEMEDNMedizin- und Informationstechnik AG\"},\"image\":{\"@id\":\"https:\\\/\\\/www.getemed.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.getemed.de\\\/de\\\/#\\\/schema\\\/person\\\/89fb0914b510044ccc8cc7699942c7e1\",\"name\":\"Vishwanath Diraviam\",\"url\":\"https:\\\/\\\/www.getemed.de\\\/de\\\/author\\\/vishwa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Besuchen Sie uns auf der Arab Health 2025 - Medizin- und Informationstechnik AG","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.getemed.de\/de\/besuchen-sie-uns-auf-der-arab-health-2025\/","og_locale":"de_DE","og_type":"article","og_title":"Besuchen Sie uns auf der Arab Health 2025 - Medizin- und Informationstechnik AG","og_description":"Besuchen Sie uns auf der Arab Health 2025 16. Januar 2025 Bei der diesj\u00e4hrigen Arab Health vom 27.-30.01.25 wird GETEMED gemeinsam mit seinen Partnern auf dem Gemeinschaftsstand von Th\u00fcringen seine [&hellip;]","og_url":"https:\/\/www.getemed.de\/de\/besuchen-sie-uns-auf-der-arab-health-2025\/","og_site_name":"Medizin- und Informationstechnik AG","article_published_time":"2025-01-16T12:44:42+00:00","article_modified_time":"2025-01-16T13:06:07+00:00","og_image":[{"url":"https:\/\/www.getemed.de\/wp-content\/uploads\/Dubai.png","type":"","width":"","height":""}],"author":"Vishwanath Diraviam","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Vishwanath Diraviam","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.getemed.de\/besuchen-sie-uns-auf-der-arab-health-2025\/#article","isPartOf":{"@id":"https:\/\/www.getemed.de\/besuchen-sie-uns-auf-der-arab-health-2025\/"},"author":{"name":"Vishwanath Diraviam","@id":"https:\/\/www.getemed.de\/de\/#\/schema\/person\/89fb0914b510044ccc8cc7699942c7e1"},"headline":"Besuchen Sie uns auf der Arab Health 2025","datePublished":"2025-01-16T12:44:42+00:00","dateModified":"2025-01-16T13:06:07+00:00","mainEntityOfPage":{"@id":"https:\/\/www.getemed.de\/besuchen-sie-uns-auf-der-arab-health-2025\/"},"wordCount":91,"publisher":{"@id":"https:\/\/www.getemed.de\/de\/#organization"},"image":{"@id":"https:\/\/www.getemed.de\/besuchen-sie-uns-auf-der-arab-health-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/www.getemed.de\/wp-content\/uploads\/Dubai.png","inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.getemed.de\/besuchen-sie-uns-auf-der-arab-health-2025\/","url":"https:\/\/www.getemed.de\/besuchen-sie-uns-auf-der-arab-health-2025\/","name":"Besuchen Sie uns auf der Arab Health 2025 - Medizin- und Informationstechnik AG","isPartOf":{"@id":"https:\/\/www.getemed.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.getemed.de\/besuchen-sie-uns-auf-der-arab-health-2025\/#primaryimage"},"image":{"@id":"https:\/\/www.getemed.de\/besuchen-sie-uns-auf-der-arab-health-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/www.getemed.de\/wp-content\/uploads\/Dubai.png","datePublished":"2025-01-16T12:44:42+00:00","dateModified":"2025-01-16T13:06:07+00:00","inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.getemed.de\/besuchen-sie-uns-auf-der-arab-health-2025\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.getemed.de\/besuchen-sie-uns-auf-der-arab-health-2025\/#primaryimage","url":"https:\/\/www.getemed.de\/wp-content\/uploads\/Dubai.png","contentUrl":"https:\/\/www.getemed.de\/wp-content\/uploads\/Dubai.png"},{"@type":"WebSite","@id":"https:\/\/www.getemed.de\/de\/#website","url":"https:\/\/www.getemed.de\/de\/","name":"GETEMED Medizin- und Informationstechnik AG","description":"","publisher":{"@id":"https:\/\/www.getemed.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.getemed.de\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.getemed.de\/de\/#organization","name":"GETEMEDNMedizin- und Informationstechnik AG","url":"https:\/\/www.getemed.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.getemed.de\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.getemed.de\/wp-content\/uploads\/Logo_GETEMED.png","contentUrl":"https:\/\/www.getemed.de\/wp-content\/uploads\/Logo_GETEMED.png","width":1471,"height":305,"caption":"GETEMEDNMedizin- und Informationstechnik AG"},"image":{"@id":"https:\/\/www.getemed.de\/de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.getemed.de\/de\/#\/schema\/person\/89fb0914b510044ccc8cc7699942c7e1","name":"Vishwanath Diraviam","url":"https:\/\/www.getemed.de\/de\/author\/vishwa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.getemed.de\/de\/wp-json\/wp\/v2\/posts\/8398","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.getemed.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.getemed.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.getemed.de\/de\/wp-json\/wp\/v2\/users\/219149283"}],"replies":[{"embeddable":true,"href":"https:\/\/www.getemed.de\/de\/wp-json\/wp\/v2\/comments?post=8398"}],"version-history":[{"count":5,"href":"https:\/\/www.getemed.de\/de\/wp-json\/wp\/v2\/posts\/8398\/revisions"}],"predecessor-version":[{"id":8408,"href":"https:\/\/www.getemed.de\/de\/wp-json\/wp\/v2\/posts\/8398\/revisions\/8408"}],"wp:attachment":[{"href":"https:\/\/www.getemed.de\/de\/wp-json\/wp\/v2\/media?parent=8398"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.getemed.de\/de\/wp-json\/wp\/v2\/categories?post=8398"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.getemed.de\/de\/wp-json\/wp\/v2\/tags?post=8398"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}